{"id":4754,"count":2,"description":"","link":"https:\/\/andysowards.com\/blog\/tag\/space-ship\/","name":"space-ship","slug":"space-ship","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>space-ship Archives - Daily Business Resources for Entrepreneurs, Web Designers, &amp; Creatives by Andy Sowards<\/title>\n<meta name=\"description\" content=\"space-ship,\" \/>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"space-ship Archives - Daily Business Resources for Entrepreneurs, Web Designers, &amp; Creatives by Andy Sowards\" \/>\n<meta property=\"og:description\" content=\"space-ship,\" \/>\n<meta property=\"og:url\" content=\"https:\/\/andysowards.com\/blog\/tag\/space-ship\/\" \/>\n<meta property=\"og:site_name\" content=\"Daily Business Resources for Entrepreneurs, Web Designers, &amp; Creatives by Andy Sowards\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@andysowards\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/andysowards.com\\\/blog\\\/tag\\\/space-ship\\\/\",\"url\":\"https:\\\/\\\/andysowards.com\\\/blog\\\/tag\\\/space-ship\\\/\",\"name\":\"space-ship Archives - Daily Business Resources for Entrepreneurs, Web Designers, &amp; Creatives by Andy Sowards\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/andysowards.com\\\/blog\\\/#website\"},\"description\":\"space-ship,\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/andysowards.com\\\/blog\\\/tag\\\/space-ship\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/andysowards.com\\\/blog\\\/tag\\\/space-ship\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/andysowards.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"space-ship\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/andysowards.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/andysowards.com\\\/blog\\\/\",\"name\":\"Daily Business Resources for Entrepreneurs, Web Designers, &amp; Creatives by Andy Sowards\",\"description\":\"Design Inspiration &amp; Business Resources for Creatives\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/andysowards.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"space-ship Archives - Daily Business Resources for Entrepreneurs, Web Designers, &amp; Creatives by Andy Sowards","description":"space-ship,","robots":{"index":"noindex","follow":"follow"},"og_locale":"en_US","og_type":"article","og_title":"space-ship Archives - Daily Business Resources for Entrepreneurs, Web Designers, &amp; Creatives by Andy Sowards","og_description":"space-ship,","og_url":"https:\/\/andysowards.com\/blog\/tag\/space-ship\/","og_site_name":"Daily Business Resources for Entrepreneurs, Web Designers, &amp; Creatives by Andy Sowards","twitter_card":"summary_large_image","twitter_site":"@andysowards","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/andysowards.com\/blog\/tag\/space-ship\/","url":"https:\/\/andysowards.com\/blog\/tag\/space-ship\/","name":"space-ship Archives - Daily Business Resources for Entrepreneurs, Web Designers, &amp; Creatives by Andy Sowards","isPartOf":{"@id":"https:\/\/andysowards.com\/blog\/#website"},"description":"space-ship,","breadcrumb":{"@id":"https:\/\/andysowards.com\/blog\/tag\/space-ship\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/andysowards.com\/blog\/tag\/space-ship\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/andysowards.com\/blog\/"},{"@type":"ListItem","position":2,"name":"space-ship"}]},{"@type":"WebSite","@id":"https:\/\/andysowards.com\/blog\/#website","url":"https:\/\/andysowards.com\/blog\/","name":"Daily Business Resources for Entrepreneurs, Web Designers, &amp; Creatives by Andy Sowards","description":"Design Inspiration &amp; Business Resources for Creatives","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/andysowards.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/andysowards.com\/blog\/wp-json\/wp\/v2\/tags\/4754","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/andysowards.com\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/andysowards.com\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/andysowards.com\/blog\/wp-json\/wp\/v2\/posts?tags=4754"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}